{"id":9890,"date":"2024-06-03T20:02:35","date_gmt":"2024-06-03T18:02:35","guid":{"rendered":"http:\/\/fenetresurblog.com\/?p=9890"},"modified":"2024-06-03T20:02:35","modified_gmt":"2024-06-03T18:02:35","slug":"stephane-leneuf-laube-du-mal-editions-michel-lafon","status":"publish","type":"post","link":"https:\/\/fenetresurblog.com\/index.php\/2024\/06\/03\/stephane-leneuf-laube-du-mal-editions-michel-lafon\/","title":{"rendered":"STEPHANE LENEUF \u00ab\u00a0L&rsquo;AUBE DU MAL\u00a0\u00bb Editions Michel Lafon"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9891\" src=\"http:\/\/fenetresurblog.com\/wp-content\/uploads\/2024\/06\/L_Aube_du_mal_hd-186x300.png\" alt=\"\" width=\"186\" height=\"300\" srcset=\"https:\/\/fenetresurblog.com\/wp-content\/uploads\/2024\/06\/L_Aube_du_mal_hd-186x300.png 186w, https:\/\/fenetresurblog.com\/wp-content\/uploads\/2024\/06\/L_Aube_du_mal_hd-768x1240.png 768w, https:\/\/fenetresurblog.com\/wp-content\/uploads\/2024\/06\/L_Aube_du_mal_hd-634x1024.png 634w, https:\/\/fenetresurblog.com\/wp-content\/uploads\/2024\/06\/L_Aube_du_mal_hd.png 1400w\" sizes=\"auto, (max-width: 186px) 100vw, 186px\" \/><\/p>\n<p><span style=\"color: #00ff00;\"><strong>Sur fond d\u2019Occupation et de R\u00e9sistance, le destin bouleversant d\u2019une m\u00e8re qui va voir l\u2019Histoire d\u00e9chirer sa famille.<\/strong><\/span><\/p>\n<p><strong><span style=\"color: #00ff00;\">Alsace, 1918. Tandis que la France c\u00e9l\u00e8bre sa victoire, Marie voit Bernhard, son mari allemand, la quitter, emmenant outre-Rhin l\u2019un de leurs jumeaux, \u00e2g\u00e9s de quelques mois \u00e0 peine. Commence alors pour elle une vie de veuve de guerre o\u00f9 elle doit porter ce secret, gardant toujours l\u2019espoir de r\u00e9unir les siens, m\u00eame lorsqu\u2019\u00e9clate le conflit avec l\u2019Allemagne du IIIe Reich. M\u00e8re courage, r\u00e9sistante de la premi\u00e8re heure, elle s\u2019engage contre la barbarie nazie, sans savoir que le destin pourrait la livrer \u00e0 ce fils qu\u2019elle n\u2019a jamais revu, et devenu officier SS<\/span><\/strong>.<\/p>\n<p>INTERVIEW DE St\u00e9phane LENEUF<\/p>\n<p><iframe loading=\"lazy\" title=\"INTERVIEW DE St\u00e9phane LENEUF  pour  &quot;L AUBE DU MAL&quot; Editions Michel Lafon\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/YNm_OMLMcOg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sur fond d\u2019Occupation et de R\u00e9sistance, le destin bouleversant d\u2019une m\u00e8re qui va voir l\u2019Histoire d\u00e9chirer sa famille. Alsace, 1918. Tandis que la France c\u00e9l\u00e8bre sa victoire, Marie voit Bernhard, son mari allemand, la quitter, emmenant outre-Rhin l\u2019un de leurs jumeaux, \u00e2g\u00e9s de quelques mois \u00e0 peine. Commence alors pour elle une vie de veuve &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fenetresurblog.com\/index.php\/2024\/06\/03\/stephane-leneuf-laube-du-mal-editions-michel-lafon\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;STEPHANE LENEUF \u00ab\u00a0L&rsquo;AUBE DU MAL\u00a0\u00bb Editions Michel Lafon&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9890","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/posts\/9890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/comments?post=9890"}],"version-history":[{"count":0,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/posts\/9890\/revisions"}],"wp:attachment":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/media?parent=9890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/categories?post=9890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/tags?post=9890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}