{"id":9531,"date":"2023-11-12T13:25:18","date_gmt":"2023-11-12T12:25:18","guid":{"rendered":"http:\/\/fenetresurblog.com\/?p=9531"},"modified":"2023-11-12T13:25:18","modified_gmt":"2023-11-12T12:25:18","slug":"magiementalisme-taha-mansour-dans-leffet-papillon-studio-hebertot-paris-la-mysterieuse-histoire-de-thomas-polgarast-theo-theatre-paris","status":"publish","type":"post","link":"https:\/\/fenetresurblog.com\/index.php\/2023\/11\/12\/magiementalisme-taha-mansour-dans-leffet-papillon-studio-hebertot-paris-la-mysterieuse-histoire-de-thomas-polgarast-theo-theatre-paris\/","title":{"rendered":"MAGIE\/MENTALISME : Taha Mansour dans L&rsquo;effet Papillon Studio Hebertot, Paris &#038;  La myst\u00e9rieuse histoire de Thomas Polgarast Th\u00e9o Th\u00e9\u00e2tre, Paris"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9532\" src=\"http:\/\/fenetresurblog.com\/wp-content\/uploads\/2023\/11\/vz-5f53f7b9-5b07-4164-b21e-1adfd3537010-200x300.jpeg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/fenetresurblog.com\/wp-content\/uploads\/2023\/11\/vz-5f53f7b9-5b07-4164-b21e-1adfd3537010-200x300.jpeg 200w, https:\/\/fenetresurblog.com\/wp-content\/uploads\/2023\/11\/vz-5f53f7b9-5b07-4164-b21e-1adfd3537010.jpeg 533w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/p>\n<p>Deux spectacles propos\u00e9s par <a href=\"https:\/\/www.tahamansour.com\/\" target=\"_blank\" rel=\"noopener\">TAHA MANSOUR,\u00a0<\/a> mentaliste \u00e0 Paris et en tourn\u00e9 A d\u00e9couvrir !<\/p>\n<p><span style=\"color: #00ff00;\"><strong>Un voyage po\u00e9tique et myst\u00e9rieux o\u00f9 vous serez invit\u00e9s \u00e0 remettre en question votre perception du monde, et o\u00f9 chacun de vos choix compte.<\/strong><\/span><\/p>\n<div id=\"speDescription\">\n<p><span style=\"color: #00ff00;\"><strong>Vous pensez que vos choix sont libres ? Impr\u00e9visibles ? Peut-\u00eatre pas&#8230;<\/strong><\/span><\/p>\n<p><span style=\"color: #00ff00;\"><strong>Vous avez s\u00fbrement d\u00e9j\u00e0 entendu parler de l&rsquo;Effet Papillon. D\u00e9couvert en 1961, ce ph\u00e9nom\u00e8ne insinue que les moindres petits \u00e9v\u00e8nements peuvent d\u00e9terminer des ph\u00e9nom\u00e8nes qui paraissent impr\u00e9visibles et incontr\u00f4lables. Ainsi, les battements d&rsquo;ailes d&rsquo;un papillon au Br\u00e9sil peuvent engendrer une tornade au Mexique.<\/strong><\/span><br \/>\n<span style=\"color: #00ff00;\"><strong>Et si nos choix n&rsquo;\u00e9taient donc pas vraiment libres, mais plut\u00f4t le fruit d&rsquo;un effet papillon ?<\/strong><\/span><br \/>\n<span style=\"color: #00ff00;\"><strong>Le mentaliste Taha Mansour vous invite \u00e0 un voyage mental po\u00e9tique et bluffant dans lequel vous \u00eates incit\u00e9s \u00e0 remettre en question la perception que vous avez du monde environnant. Lecture de pens\u00e9es, influence, voyance, autant de ph\u00e9nom\u00e8nes myst\u00e9rieux vous attendront lors de ce voyage&#8230;<\/strong><\/span><\/p>\n<p><span style=\"color: #00ff00;\"><strong>Ouvrez bien grands les yeux, et vivez pleinement l&rsquo;exp\u00e9rience de l&rsquo;Effet Papillon !\u00a0<\/strong><\/span><\/p>\n<p><iframe loading=\"lazy\" title=\"TAHA MANSOUR  &quot;L&#039;EFFET PAPILLON&quot; et &quot;LA MYSTERIEUSE HISTOIRE DE THOMAS POLGARAST&quot;\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/GKbDqsqArek?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><strong style=\"color: #00ff00; font-size: 1.5rem;\"><span class=\"summary\">La Myst\u00e9rieuse histoire de Thomas Polgarast<\/span><\/strong><\/p>\n<\/div>\n<div>\n<p><span style=\"color: #00ff00;\"><strong><span class=\"lieug\"><a href=\"https:\/\/www.billetreduc.com\/lieu\/paris\/theo-theatre\/\">Th\u00e9o Th\u00e9\u00e2tre, Paris<\/a><\/span><\/strong><\/span><\/p>\n<\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9533\" src=\"http:\/\/fenetresurblog.com\/wp-content\/uploads\/2023\/11\/vz-49932e9b-f2dd-4426-a5d4-0d5fc06e0552-215x300.jpeg\" alt=\"\" width=\"215\" height=\"300\" srcset=\"https:\/\/fenetresurblog.com\/wp-content\/uploads\/2023\/11\/vz-49932e9b-f2dd-4426-a5d4-0d5fc06e0552-215x300.jpeg 215w, https:\/\/fenetresurblog.com\/wp-content\/uploads\/2023\/11\/vz-49932e9b-f2dd-4426-a5d4-0d5fc06e0552.jpeg 573w\" sizes=\"auto, (max-width: 215px) 100vw, 215px\" \/><\/div>\n<div><\/div>\n<p><!--more--><\/p>\n<div>\n<h6><strong><span style=\"color: #00ff00;\">Un conte moderne m\u00ealant th\u00e9\u00e2tre et mentalisme&#8230; \u00cates-vous pr\u00eats \u00e0 vivre cette exp\u00e9rience in\u00e9dite ?<\/span><\/strong><\/h6>\n<div id=\"speDescription\">\n<p><strong><span style=\"color: #00ff00;\">Thomas Polgarast, un voyant ayant perdu sa femme, re\u00e7oit un coffre ferm\u00e9 avec pour seule inscription : \u00ab\u00a0Retrouve moi&#8230;\u00a0\u00bb. Un spectacle o\u00f9 les personnages sont&#8230; vous !<\/span><\/strong><\/p>\n<p><strong><span style=\"color: #00ff00;\">21h35. Alors que Thomas s&rsquo;appr\u00eate \u00e0 rentrer chez lui apr\u00e8s le tournage du dernier \u00e9pisode de son \u00e9mission, il re\u00e7oit un appel lui annon\u00e7ant que sa femme n&rsquo;est plus de ce monde&#8230; Passent des ann\u00e9es durant lesquelles il essaie en vain de la contacter \u00e0 travers divers m\u00e9diums, mais il n&rsquo;obtient que tromperie et mensonges. Il d\u00e9cide alors d&rsquo;utiliser ses talents pour se faire passer pour un voyant, afin de redonner de l&rsquo;espoir aux gens, un espoir que lui sait ne pourra retrouver.<\/span><\/strong><br \/>\n<strong><span style=\"color: #00ff00;\">Jusqu&rsquo;au jour o\u00f9 un myst\u00e9rieux coffre fait son apparition devant sa porte d&rsquo;entr\u00e9e&#8230;<\/span><\/strong><\/p>\n<p><strong><span style=\"color: #00ff00;\">Le Saviez-vous?<\/span><\/strong><br \/>\n<strong><span style=\"color: #00ff00;\">Apr\u00e8s son premier spectacle nomm\u00e9 aux Petits Moli\u00e8res, L&rsquo;Effet Papillon, le mentaliste Taha Mansour revient avec un spectacle po\u00e9tique in\u00e9dit. En m\u00e9langeant performance th\u00e9\u00e2trale, voyance, lecture de pens\u00e9es et hypnose, Taha Mansour vous propose un spectacle puissant que vous n&rsquo;\u00eates pas pr\u00e8s d&rsquo;oublier&#8230;<\/span><\/strong><\/p>\n<p><strong><span style=\"color: #00ff00;\">Vivez un moment myst\u00e9rieux o\u00f9 vous devenez personnages de l&rsquo;histoire.<\/span><\/strong><br \/>\n<strong><span style=\"color: #00ff00;\">O\u00f9 le 4e mur n&rsquo;existe plus.<\/span><\/strong><br \/>\n<strong><span style=\"color: #00ff00;\">O\u00f9 la barri\u00e8re entre r\u00e9alit\u00e9 et imaginaire devient presque inexistante&#8230;<\/span><\/strong><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Deux spectacles propos\u00e9s par TAHA MANSOUR,\u00a0 mentaliste \u00e0 Paris et en tourn\u00e9 A d\u00e9couvrir ! Un voyage po\u00e9tique et myst\u00e9rieux o\u00f9 vous serez invit\u00e9s \u00e0 remettre en question votre perception du monde, et o\u00f9 chacun de vos choix compte. Vous pensez que vos choix sont libres ? Impr\u00e9visibles ? Peut-\u00eatre pas&#8230; Vous avez s\u00fbrement &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fenetresurblog.com\/index.php\/2023\/11\/12\/magiementalisme-taha-mansour-dans-leffet-papillon-studio-hebertot-paris-la-mysterieuse-histoire-de-thomas-polgarast-theo-theatre-paris\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;MAGIE\/MENTALISME : Taha Mansour dans L&rsquo;effet Papillon Studio Hebertot, Paris &#038;  La myst\u00e9rieuse histoire de Thomas Polgarast Th\u00e9o Th\u00e9\u00e2tre, Paris&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9531","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/posts\/9531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/comments?post=9531"}],"version-history":[{"count":0,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/posts\/9531\/revisions"}],"wp:attachment":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/media?parent=9531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/categories?post=9531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/tags?post=9531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}