{"id":9078,"date":"2022-06-09T11:36:15","date_gmt":"2022-06-09T09:36:15","guid":{"rendered":"http:\/\/fenetresurblog.com\/?p=9078"},"modified":"2022-06-09T11:36:15","modified_gmt":"2022-06-09T09:36:15","slug":"roman-esoterique-eric-de-lestoile-12-editions-detrand-interview","status":"publish","type":"post","link":"https:\/\/fenetresurblog.com\/index.php\/2022\/06\/09\/roman-esoterique-eric-de-lestoile-12-editions-detrand-interview\/","title":{"rendered":"ROMAN \u00c9SOT\u00c9RIQUE  :  Eric de l&rsquo;ESTOILE  \u00ab\u00a012\u00a0\u00bb Editions Detrand  (Interview)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9028\" src=\"http:\/\/fenetresurblog.com\/wp-content\/uploads\/2022\/06\/71bT4-NTU4L-187x300.jpg\" alt=\"\" width=\"187\" height=\"300\" srcset=\"https:\/\/fenetresurblog.com\/wp-content\/uploads\/2022\/06\/71bT4-NTU4L-187x300.jpg 187w, https:\/\/fenetresurblog.com\/wp-content\/uploads\/2022\/06\/71bT4-NTU4L-768x1233.jpg 768w, https:\/\/fenetresurblog.com\/wp-content\/uploads\/2022\/06\/71bT4-NTU4L-638x1024.jpg 638w, https:\/\/fenetresurblog.com\/wp-content\/uploads\/2022\/06\/71bT4-NTU4L.jpg 1029w\" sizes=\"auto, (max-width: 187px) 100vw, 187px\" \/><\/p>\n<p><span style=\"color: #00ff00;\"><strong>Hugo, arch\u00e9ologue et passionn\u00e9 d\u2019\u00e9sot\u00e9risme, d\u00e9couvre au fond d\u2019une crypte une myst\u00e9rieuse relique, qui l\u2019entra\u00eene dans une fantastique qu\u00eate initiatique.De l\u2019incroyable aventure des Templiers \u00e0 la conqu\u00eate de l\u2019Arche d\u2019Alliance, jusqu\u2019aux soci\u00e9t\u00e9s secr\u00e8tes actuelles ; de Bugarach \u00e0 l\u2019\u00c9gypte en passant par Chartres, Les A\u00e7ores, Bimini et Tiahuanaco, Hugo remonte jusqu\u2019aux origines les plus secr\u00e8tes de l\u2019humanit\u00e9 o\u00f9 l\u2019initiation aux Myst\u00e8res se fait par la transmission de symboles\u2026 et du chiffre 12.Ce roman est un triptyque,..<\/strong><\/span>.<\/p>\n<p>INTERVIEW D&rsquo;ERIC DE\u00a0 L&rsquo;ESTOILE<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-9078-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/fenetresurblog.com\/wp-content\/uploads\/2022\/06\/ERIC-DE-L-ESTOILE-radio.mp3?_=1\" \/><a href=\"http:\/\/fenetresurblog.com\/wp-content\/uploads\/2022\/06\/ERIC-DE-L-ESTOILE-radio.mp3\">http:\/\/fenetresurblog.com\/wp-content\/uploads\/2022\/06\/ERIC-DE-L-ESTOILE-radio.mp3<\/a><\/audio>\n","protected":false},"excerpt":{"rendered":"<p>Hugo, arch\u00e9ologue et passionn\u00e9 d\u2019\u00e9sot\u00e9risme, d\u00e9couvre au fond d\u2019une crypte une myst\u00e9rieuse relique, qui l\u2019entra\u00eene dans une fantastique qu\u00eate initiatique.De l\u2019incroyable aventure des Templiers \u00e0 la conqu\u00eate de l\u2019Arche d\u2019Alliance, jusqu\u2019aux soci\u00e9t\u00e9s secr\u00e8tes actuelles ; de Bugarach \u00e0 l\u2019\u00c9gypte en passant par Chartres, Les A\u00e7ores, Bimini et Tiahuanaco, Hugo remonte jusqu\u2019aux origines les plus secr\u00e8tes &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fenetresurblog.com\/index.php\/2022\/06\/09\/roman-esoterique-eric-de-lestoile-12-editions-detrand-interview\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;ROMAN \u00c9SOT\u00c9RIQUE  :  Eric de l&rsquo;ESTOILE  \u00ab\u00a012\u00a0\u00bb Editions Detrand  (Interview)&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9078","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/posts\/9078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/comments?post=9078"}],"version-history":[{"count":0,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/posts\/9078\/revisions"}],"wp:attachment":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/media?parent=9078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/categories?post=9078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/tags?post=9078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}