{"id":2063,"date":"2017-08-16T17:47:07","date_gmt":"2017-08-16T15:47:07","guid":{"rendered":"http:\/\/fenetresurblog.com\/?p=2063"},"modified":"2017-11-01T23:22:28","modified_gmt":"2017-11-01T22:22:28","slug":"viktor-vincent-le-mentaliste-revient-avec-un-nouveau-spectacle-a-la-comedie-des-champs-elysees-a-partir-du-28-septembre","status":"publish","type":"post","link":"https:\/\/fenetresurblog.com\/index.php\/2017\/08\/16\/viktor-vincent-le-mentaliste-revient-avec-un-nouveau-spectacle-a-la-comedie-des-champs-elysees-a-partir-du-28-septembre\/","title":{"rendered":"VIKTOR VINCENT le mentaliste revient avec un  NOUVEAU SPECTACLE \u00e0 la Com\u00e9die des Champs Elys\u00e9es \u00e0 partir du 28 septembre (Interview)"},"content":{"rendered":"<p><em><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2064\" src=\"http:\/\/fenetresurblog.com\/wp-content\/uploads\/2017\/08\/cache_8054397-201x300.jpg\" alt=\"\" width=\"201\" height=\"300\" srcset=\"https:\/\/fenetresurblog.com\/wp-content\/uploads\/2017\/08\/cache_8054397-201x300.jpg 201w, https:\/\/fenetresurblog.com\/wp-content\/uploads\/2017\/08\/cache_8054397.jpg 311w\" sizes=\"auto, (max-width: 201px) 100vw, 201px\" \/><\/em><\/p>\n<p><span style=\"color: #ff00ff;\"><strong><em>\u00a0\u00bb Votre vie change la vie<\/em><\/strong><\/span><\/p>\n<p><span style=\"color: #ff00ff;\"><strong><em>de millions de personnes<\/em><\/strong><\/span><\/p>\n<p><span style=\"color: #ff00ff;\"><strong><em>que vous ne rencontrerez jamais. \u00ab\u00a0<\/em><\/strong><\/span><\/p>\n<p><span style=\"color: #ff00ff;\"><strong>\u00a0 \u00a0 \u00a0Tout commence par le r\u00e9cit de trois histoires vraies, des histoires si incroyables, si improbables qu\u2019elles interrogent\u2026 Et si le hasard n\u2019existait pas ?<\/strong><\/span>\u00a0<span style=\"color: #ff00ff;\"><strong>&#8230;<\/strong><\/span><!--more--><\/p>\n<p>Et si nos destins \u00e9taient li\u00e9s ? A partir de ces hypoth\u00e8ses, Viktor vous invite \u00e0 percevoir le monde autrement et tisse des liens insoup\u00e7onn\u00e9s \u00e0 travers le temps et l\u2019espace. Vous suivrez les pas d\u2019une jeune New Yorkaise, d\u2019un laboureur Ukrainien du XIX \u00e8me si\u00e8cle et d\u2019une bande d\u2019\u00e9tudiants des ann\u00e9es 50 pour d\u00e9couvrir que leurs destins et le n\u00f4tre sont connect\u00e9s, bien au-del\u00e0 de ce que nous pouvons imaginer. Une exp\u00e9rience intime, visuelle et intrigante qui vous emportera aux fronti\u00e8res du fantastique.<\/p>\n<p>Viktor Vincent \u00e9tait attendu, car apr\u00e8s son dernier spectacle \u00a0\u00bb Emprise\u00a0\u00bb, il lui fallait faire encore plus fort. Si aujourd&rsquo;hui, magie rime avec mentalisme, ce volet du noble art et mis \u00e0 rude \u00e9preuve. Le public en veut plus. encore plus fort. Il faut comme Uri Geller qui dans les ann\u00e9es 70 avait pr\u00e9tendu avoir des pouvoirs de psychokin\u00e9sie et de t\u00e9l\u00e9pathie faire croire que certains poss\u00e8dent des dons ou le Don. Viktor vincent pose les choses tout d&rsquo;entr\u00e9e : Non il n&rsquo;a pas de Pouvoirs ! Ce que vous allez voir n&rsquo;est oserais-je dire que de la Magie.<\/p>\n<p>Mais comment fait t-il pour que apr\u00e8s moult m\u00e9langes d&rsquo;un jeu de cartes par un spectateur, puis cartes choisies librement par le spectateur , que les valeurs de celles ci correspondent \u00e0 sa date de naissance ? Rien que cet effet vaut le prix du billet !<\/p>\n<p>Viktor Vincent \u00e0 construit ce spectacle autour d&rsquo;histoires qui se d\u00e9roulent dans des espaces spatio-temporels diff\u00e9rents, que rien ne semble relier entre elles. Et pourtant ! Facile direz-vous ? Mais comment alors votre propre histoire \u00e0 vous spectateur va t-elle se raccrocher \u00e0 ces personnages dont vous ne soup\u00e7onniez\u00a0pas l&rsquo;existance?\u00a0 Comment un \u00e9v\u00e8nement du XIX\u00b0 si\u00e8cle peut avoir une incidence sur vous, oui vous assis en ce moment\u00a0 dans votre fauteuil, au th\u00e9\u00e2tre?\u00a0 C&rsquo;est ce que nous r\u00e9v\u00e8le, enfin presque, Viktor Vincent dans ce spectacle. Et si vous lisez ces lignes, ce n&rsquo;est\u00a0 pas le hasard &#8230;?\u00a0 \u00ab\u00a0Les liens invisibles\u00a0\u00bb fils t\u00e9nus et fragiles racontent nos Histoires comme les lignes de notre main servent \u00e0 pr\u00e9dire l&rsquo;avenir. Faut t-il y croire ou pas? Finalement Viktor Vincent manipule ces liens invisibles\u00a0 comme un marionnettiste et nous fait franchir le miroir de nos illusions.<\/p>\n<p><a href=\"https:\/\/www.viktorvincent.fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">VIKTOR VINCENT<\/a><\/p>\n<p><a href=\"http:\/\/www.3emeacte.com\/comediedeschampselysees\/Seances.aspx?manif=00000000-0000-0000-0085-000000000077\" target=\"_blank\" rel=\"noopener noreferrer\">Com\u00e9die des Champs Elys\u00e9es <\/a>\u00e0 partir du 28 septembre<\/p>\n<p><iframe loading=\"lazy\" title=\"ENTREVUE VIKTOR VINCENT comedie des Champs Elys\u00e9es\" frameborder=\"0\" width=\"525\" height=\"295\" src=\"https:\/\/geo.dailymotion.com\/player.html?video=x5xr0ge&#038;\" allowfullscreen allow=\"autoplay; fullscreen; picture-in-picture; web-share\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00bb Votre vie change la vie de millions de personnes que vous ne rencontrerez jamais. \u00ab\u00a0 \u00a0 \u00a0 \u00a0Tout commence par le r\u00e9cit de trois histoires vraies, des histoires si incroyables, si improbables qu\u2019elles interrogent\u2026 Et si le hasard n\u2019existait pas ?\u00a0&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2063","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/posts\/2063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/comments?post=2063"}],"version-history":[{"count":0,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/posts\/2063\/revisions"}],"wp:attachment":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/media?parent=2063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/categories?post=2063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/tags?post=2063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}