{"id":10715,"date":"2026-05-13T10:16:45","date_gmt":"2026-05-13T08:16:45","guid":{"rendered":"https:\/\/fenetresurblog.com\/?p=10715"},"modified":"2026-05-13T10:23:55","modified_gmt":"2026-05-13T08:23:55","slug":"thriller-frederique-molay-anthropodermia-ed-lanimal","status":"publish","type":"post","link":"https:\/\/fenetresurblog.com\/index.php\/2026\/05\/13\/thriller-frederique-molay-anthropodermia-ed-lanimal\/","title":{"rendered":"THRILLER : FR\u00c9D\u00c9RIQUE  MOLAY \u00ab\u00a0ANTHROPODERMIA\u00a0\u00bb \u00c9d L&rsquo;ANIMAL"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"678\" height=\"1024\" src=\"https:\/\/fenetresurblog.com\/wp-content\/uploads\/2026\/05\/Numerisation_20260507-2-678x1024.jpg\" alt=\"\" class=\"wp-image-10717\" style=\"aspect-ratio:0.662113002501957;width:201px;height:auto\" srcset=\"https:\/\/fenetresurblog.com\/wp-content\/uploads\/2026\/05\/Numerisation_20260507-2-678x1024.jpg 678w, https:\/\/fenetresurblog.com\/wp-content\/uploads\/2026\/05\/Numerisation_20260507-2-199x300.jpg 199w, https:\/\/fenetresurblog.com\/wp-content\/uploads\/2026\/05\/Numerisation_20260507-2-768x1159.jpg 768w, https:\/\/fenetresurblog.com\/wp-content\/uploads\/2026\/05\/Numerisation_20260507-2-1018x1536.jpg 1018w, https:\/\/fenetresurblog.com\/wp-content\/uploads\/2026\/05\/Numerisation_20260507-2-1357x2048.jpg 1357w, https:\/\/fenetresurblog.com\/wp-content\/uploads\/2026\/05\/Numerisation_20260507-2-scaled.jpg 1696w\" sizes=\"auto, (max-width: 678px) 100vw, 678px\" \/><\/figure>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color has-link-color has-medium-font-size wp-elements-25e40b099f6fb73c349b77d944e8017f\"><strong>L\u2019AUTEURE: Fr\u00e9d\u00e9rique Molay travaille depuis des ann\u00e9es dans les coulisses du monde politique. La nuit, elle fouille la face sombre des hommes dans ses romans policiers. Prix du Quai des Orf\u00e8vres avec son best-seller La 7e femme, \u00e0 l&rsquo;origine d&rsquo;une s\u00e9rie, elle revient avec un volume plus gla\u00e7ant encore.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Fr\u00e9d\u00e9rique MOLAY  &quot;ANTHROPODERMIA&quot; \u00c9ditions L&#039;Animal INTERVIEW\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/29r8KB-O3dU?start=7&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color has-link-color has-medium-font-size wp-elements-49263ec2bb5f6ebec58f65af836a484e\"><strong>Paris, 1475, dans une maison close au pied de Notre-Dame, le meurtre de la jeune Agn\u00e8s ne laisse pas tout le monde indiff\u00e9rent. Istanbul aujourd\u2019hui. Pourquoi Harper est-elle enlev\u00e9e par le meilleur ami de son p\u00e8re ? Et qu\u2019est devenu le beau Jean Malet dans le cabaret que fr\u00e9quentait le gratin nazi, alors qu\u2019il s\u2019appr\u00eatait \u00e0 fuir la capitale\u2009? \u00c0 Paris, quand Laurine Arrio est retrouv\u00e9e morte dans des circonstances suspectes, Samuel, un homme du Pr\u00e9sident, et Katell, commissaire \u00e0 la brigade criminelle du 36, plongent dans une sombre affaire\u2026 L\u2019enqu\u00eate prend une dimension internationale lorsqu\u2019elle croise le chemin de la mafia russe et d\u2019un trafic d\u2019\u0153uvres sans pr\u00e9c\u00e9dent. Des vols dans les biblioth\u00e8ques les plus prestigieuses, des meurtres d\u2019une cruaut\u00e9 effroyable, du Moyen \u00c2ge \u00e0 l\u2019Occupation, de Paris au Bosphore, d\u00e9clenchent une course contre la montre pour sauver les prochaines victimes inscrites sur une liste noire et \u00e9viter un scandale d\u2019\u00c9tat. Mais qui est le myst\u00e9rieux Monsieur Gauthier, qui semble traverser les \u00e2ges et dont les pratiques rappellent les heures les plus sombres\u2009? Dans ce thriller \u00e9rudit et gla\u00e7ant, chaque page rapproche le lecteur d\u2019une r\u00e9v\u00e9lation aussi fascinante que terrifiante.<\/strong><\/p>\n\n\n\n<p class=\"has-vivid-green-cyan-color has-text-color has-link-color has-medium-font-size wp-elements-8c9fb4e938235dfb290f266afdd7ad01\"><strong>Prix du Quai des Orf\u00e8vres avec son best-seller \u00ab&nbsp;La 7e femme&nbsp;\u00bb Fr\u00e9d\u00e9rique Molay nous entra\u00eene dans une enqu\u00eate qui prend une dimension internationale lorsqu\u2019elle croise le chemin de la mafia russe et d\u2019un trafic d\u2019\u0153uvres sans pr\u00e9c\u00e9dent. Des vols dans les biblioth\u00e8ques les plus prestigieuses, des meurtres d\u2019une cruaut\u00e9 effroyable, du Moyen \u00c2ge \u00e0 l\u2019Occupation, de Paris au Bosphore, d\u00e9clenchent une course contre la montre pour sauver les prochaines victimes inscrites sur une liste noire et \u00e9viter un scandale d\u2019\u00c9tat. Mais qui est le myst\u00e9rieux Monsieur Gauthier, qui semble traverser les \u00e2ges et dont les pratiques rappellent les heures les plus sombres\u2009? Dans ce thriller \u00e9rudit et gla\u00e7ant, chaque page rapproche le lecteur d\u2019une r\u00e9v\u00e9lation aussi fascinante que terrifiant<\/strong>e.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019AUTEURE: Fr\u00e9d\u00e9rique Molay travaille depuis des ann\u00e9es dans les coulisses du monde politique. La nuit, elle fouille la face sombre des hommes dans ses romans policiers. Prix du Quai des Orf\u00e8vres avec son best-seller La 7e femme, \u00e0 l&rsquo;origine d&rsquo;une s\u00e9rie, elle revient avec un volume plus gla\u00e7ant encore. Paris, 1475, dans une maison close &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fenetresurblog.com\/index.php\/2026\/05\/13\/thriller-frederique-molay-anthropodermia-ed-lanimal\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;THRILLER : FR\u00c9D\u00c9RIQUE  MOLAY \u00ab\u00a0ANTHROPODERMIA\u00a0\u00bb \u00c9d L&rsquo;ANIMAL&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10715","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/posts\/10715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/comments?post=10715"}],"version-history":[{"count":4,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/posts\/10715\/revisions"}],"predecessor-version":[{"id":10723,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/posts\/10715\/revisions\/10723"}],"wp:attachment":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/media?parent=10715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/categories?post=10715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/tags?post=10715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}