{"id":10606,"date":"2025-12-15T15:40:53","date_gmt":"2025-12-15T14:40:53","guid":{"rendered":"http:\/\/fenetresurblog.com\/?p=10606"},"modified":"2025-12-15T15:40:53","modified_gmt":"2025-12-15T14:40:53","slug":"polar-veronique-de-hass-lhomme-de-pierre-fayard","status":"publish","type":"post","link":"https:\/\/fenetresurblog.com\/index.php\/2025\/12\/15\/polar-veronique-de-hass-lhomme-de-pierre-fayard\/","title":{"rendered":"POLAR : V\u00c9RONIQUE DE HASS \u00ab\u00a0L&rsquo;HOMME DE PIERRE\u00a0\u00bb FAYARD"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10607\" src=\"http:\/\/fenetresurblog.com\/wp-content\/uploads\/2025\/12\/Capture-195x300.jpg\" alt=\"\" width=\"195\" height=\"300\" srcset=\"https:\/\/fenetresurblog.com\/wp-content\/uploads\/2025\/12\/Capture-195x300.jpg 195w, https:\/\/fenetresurblog.com\/wp-content\/uploads\/2025\/12\/Capture.jpg 302w\" sizes=\"auto, (max-width: 195px) 100vw, 195px\" \/><\/p>\n<p><span style=\"color: #00ff00;\"><strong>Paris, f\u00e9vrier 1934. Alors que les rues de la capitale s\u2019embrasent sous le poids des \u00e9meutes et des scandales financiers, une d\u00e9couverte macabre vient bouleverser le 36, quai des Orf\u00e8vres : treize cadavres sont retrouv\u00e9s entass\u00e9s dans la cave d\u2019un immeuble vou\u00e9 \u00e0 la destruction. La Brigade criminelle, men\u00e9e par l\u2019inspecteur principal Victor Dessange, se lance dans une enqu\u00eate haletante.<\/strong><\/span><br \/>\n<span style=\"color: #00ff00;\"><strong> Dans un Paris en pleine effervescence, o\u00f9 les milieux cach\u00e9s et les trafiquants fleurissent, Victor Dessange doit naviguer entre les tensions familiales et les secrets d\u2019une soci\u00e9t\u00e9 en mutation. D\u00e9chir\u00e9 entre sa femme et sa ma\u00eetresse, ainsi qu\u2019entre deux fils aux id\u00e9aux oppos\u00e9s, il se retrouve confront\u00e9 \u00e0 ses propres d\u00e9mons tout en traquant un tueur insaisissable.<\/strong><\/span><br \/>\n<span style=\"color: #00ff00;\"><strong> Apr\u00e8s le succ\u00e8s de<em>\u00a0La Muse rouge<\/em>, Prix du Quai des Orf\u00e8vres 2022, V\u00e9ronique de Haas nous entra\u00eene une nouvelle fois dans un polar historique captivant dont elle a le secret. Plongez dans cette fresque intrigante, o\u00f9 le pass\u00e9 \u00e9claire le pr\u00e9sent avec une intensit\u00e9 troublante.<\/strong><\/span><\/p>\n<p>INTERVIEW DE V\u00c9RONIQUE DE HASS<\/p>\n<p><iframe loading=\"lazy\" title=\"VERONIQUE DE HASS  &quot;LHOMME DE PIERRE&quot; \u00c9ditions Fayard. INTERVIEW\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/4fogieVGuUA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paris, f\u00e9vrier 1934. Alors que les rues de la capitale s\u2019embrasent sous le poids des \u00e9meutes et des scandales financiers, une d\u00e9couverte macabre vient bouleverser le 36, quai des Orf\u00e8vres : treize cadavres sont retrouv\u00e9s entass\u00e9s dans la cave d\u2019un immeuble vou\u00e9 \u00e0 la destruction. La Brigade criminelle, men\u00e9e par l\u2019inspecteur principal Victor Dessange, se &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fenetresurblog.com\/index.php\/2025\/12\/15\/polar-veronique-de-hass-lhomme-de-pierre-fayard\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;POLAR : V\u00c9RONIQUE DE HASS \u00ab\u00a0L&rsquo;HOMME DE PIERRE\u00a0\u00bb FAYARD&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10606","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/posts\/10606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/comments?post=10606"}],"version-history":[{"count":0,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/posts\/10606\/revisions"}],"wp:attachment":[{"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/media?parent=10606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/categories?post=10606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fenetresurblog.com\/index.php\/wp-json\/wp\/v2\/tags?post=10606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}